{"id":13393,"date":"2026-04-17T11:50:05","date_gmt":"2026-04-17T14:50:05","guid":{"rendered":"https:\/\/defensoriarionegro.gov.ar\/drn\/?p=13393"},"modified":"2026-04-17T12:00:22","modified_gmt":"2026-04-17T15:00:22","slug":"preocupacion-de-adpra-ante-la-grave-situacion-que-atraviesa-el-pami","status":"publish","type":"post","link":"https:\/\/defensoriarionegro.gov.ar\/drn\/preocupacion-de-adpra-ante-la-grave-situacion-que-atraviesa-el-pami\/","title":{"rendered":"Preocupaci\u00f3n de ADPRA ante la grave situaci\u00f3n que atraviesa el Pami."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Asociaci\u00f3n que nuclea a las Defensor\u00edas del Pueblo de todo el pa\u00eds (ADPRA) expres\u00f3<strong> su preocupaci\u00f3n por la cr\u00edtica situaci\u00f3n que atraviesa el Instituto Nacional de Servicios Sociales para Jubilados y Pensionados (INSSJP \u2013 PAMI) <\/strong>y el impacto que ello genera sobre el derecho a la salud de las personas mayores, cuya cobertura se encuentra directamente vinculada al acceso a beneficios jubilatorios o previsionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las Defensor\u00edas integrantes de ADPRA han relevado, en distintas jurisdicciones del pa\u00eds, un incremento sostenido de reclamos vinculados a:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cf demoras en autorizaciones de pr\u00e1cticas y tratamientos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cf falta de acceso a la provisi\u00f3n de medicamentos e insumos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cf discontinuidades en prestaciones de salud y rehabilitaci\u00f3n, asociadas a condiciones de retribuci\u00f3n irrisorias, que afectan la sostenibilidad de la red prestacional<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cf problemas en la asignaci\u00f3n y funcionamiento del sistema de m\u00e9dicos de cabecera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cf problemas en la relaci\u00f3n con prestadores de servicios de salud vinculados a condiciones de contrataci\u00f3n y pago<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cf deudas millonarias del <em>Gobierno Nacional <\/em>con los prestadores de salud en todo el pa\u00eds<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la Asociaci\u00f3n se remarc\u00f3 que el desfinanciamiento del organismo impacta de manera desproporcionada en personas mayores que dependen estructuralmente del sistema, generando situaciones de vulnerabilidad que el Estado tiene el deber de revertir de forma inmediata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ADPRA exhort\u00f3 a que las autoridades competentes adopten, con car\u00e1cter urgente, medidas coordinadas y sostenidas que permitan revertir el escenario actual por el que transita la obra social a los fines de garantizar los derechos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">constitucionales de los adultos mayores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Le\u00e9 la nota completa de ADPRA en el siguiente enlace <a href=\"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-content\/uploads\/2026\/04\/ADPRA-PAMI.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/ADPRA-PAMI.pdf<\/a><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-content\/uploads\/2026\/04\/ADPRA-PAMI-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de ADPRA-PAMI.\"><\/object><a id=\"wp-block-file--media-36b6ae65-3fb3-495e-b1b5-c441b64ceab1\" href=\"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-content\/uploads\/2026\/04\/ADPRA-PAMI-1.pdf\">ADPRA-PAMI<\/a><a href=\"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-content\/uploads\/2026\/04\/ADPRA-PAMI-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-36b6ae65-3fb3-495e-b1b5-c441b64ceab1\">Descarga<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n que nuclea a las Defensor\u00edas del Pueblo de todo el pa\u00eds (ADPRA) expres\u00f3 su preocupaci\u00f3n por la cr\u00edtica situaci\u00f3n que atraviesa el Instituto Nacional de Servicios Sociales para Jubilados y Pensionados (INSSJP \u2013 PAMI) y el impacto que ello genera sobre el derecho a la salud de las personas mayores, cuya cobertura se [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13395,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/posts\/13393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/comments?post=13393"}],"version-history":[{"count":2,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/posts\/13393\/revisions"}],"predecessor-version":[{"id":13399,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/posts\/13393\/revisions\/13399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/media\/13395"}],"wp:attachment":[{"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/media?parent=13393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/categories?post=13393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/tags?post=13393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}