{"id":14214,"date":"2026-08-12T13:00:25","date_gmt":"2026-08-12T16:00:25","guid":{"rendered":"https:\/\/defensoriarionegro.gov.ar\/drn\/?p=14214"},"modified":"2026-08-27T08:45:19","modified_gmt":"2026-08-27T11:45:19","slug":"sierra-grande-participamos-del-proceso-de-toma-de-muestras-de-agua-correspondiente-al-proyecto-minero-delta-xxi","status":"publish","type":"post","link":"https:\/\/defensoriarionegro.gov.ar\/drn\/sierra-grande-participamos-del-proceso-de-toma-de-muestras-de-agua-correspondiente-al-proyecto-minero-delta-xxi\/","title":{"rendered":"Sierra Grande: Participamos del proceso de toma de muestras de agua correspondiente al Proyecto Minero Delta XXI"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Al igual que en el resto de los proyectos mineros y energ\u00e9ticos que se vienen desarrollando en la provincia, la Defensor\u00eda del Pueblo asisti\u00f3 al muestreo participativo de aguas correspondiente a la empresa JG Fluorita S.A.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta oportunidad se trata de la \u00faltima etapa: posterior a la perforaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad se realiz\u00f3 en tres diferentes puntos: Molino Viejo \u2013 Aguas Arriba; Pit 2 PENELOPE \u2013 Aguas Centro y Molino \u2013 Aguas Abajo, ubicados a unos 15 kil\u00f3metros de Sierra Grande.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las muestras ser\u00e1n analizadas por los respectivos organismos con el fin de contrastar los resultados obtenidos en las instancias previas y evaluar si las actividades mineras han producido alg\u00fan tipo de afectaci\u00f3n en el recurso h\u00eddrico local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presencia en el territorio de la Defensor\u00eda del Pueblo, alineada a los principios de la miner\u00eda sustentable, funciona como una garant\u00eda de que el acceso a la informaci\u00f3n sea real y que la ejecuci\u00f3n de los muestreos se realice bajo par\u00e1metros de transparencia. De esta manera, se promueve una mayor rendici\u00f3n de cuentas por parte de las autoridades y de las empresas involucradas, asegurando que el manejo de los recursos naturales se realice con estricto apego al marco de los derechos humanos y la protecci\u00f3n del medio ambiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al igual que en el resto de los proyectos mineros y energ\u00e9ticos que se vienen desarrollando en la provincia, la Defensor\u00eda del Pueblo asisti\u00f3 al muestreo participativo de aguas correspondiente a la empresa JG Fluorita S.A. En esta oportunidad se trata de la \u00faltima etapa: posterior a la perforaci\u00f3n. La actividad se realiz\u00f3 en tres [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14215,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[49,250],"tags":[21],"class_list":["post-14214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-novedades","tag-ambiente-y-desarrollo-sostenible"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-content\/uploads\/2026\/08\/122323.png","_links":{"self":[{"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/posts\/14214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/comments?post=14214"}],"version-history":[{"count":1,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/posts\/14214\/revisions"}],"predecessor-version":[{"id":14216,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/posts\/14214\/revisions\/14216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/media\/14215"}],"wp:attachment":[{"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/media?parent=14214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/categories?post=14214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/defensoriarionegro.gov.ar\/drn\/wp-json\/wp\/v2\/tags?post=14214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}